{"id":51857,"date":"2025-02-28T15:55:43","date_gmt":"2025-02-28T15:55:43","guid":{"rendered":"https:\/\/molsongroup.co.uk\/?post_type=products&#038;p=32904"},"modified":"2025-12-19T10:30:50","modified_gmt":"2025-12-19T10:30:50","slug":"sennebogen-822g","status":"publish","type":"products","link":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-822g\/","title":{"rendered":"Sennebogen 822G"},"content":{"rendered":"\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center has-large-font-size\">Your 10m material handler needs for your waste and scrap applications<\/h1>\n\n\n\n<section class=\"bh-new no-color block-padding-top-50 block-padding-bottom-50\">\n\t<div class=\"container no-color image-right\">\n\t\t\t\t\t<div class=\"bh-image\" style=\"background-image: url('https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/07\/Sennebogen-822g-2-1-720x586.png');\">\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bh-content bh-centered \">\n\t\t\t<h2 data-start=\"40\" data-end=\"420\">Efficient &amp; versatile waste material handler solution<\/h2>\n<p data-start=\"40\" data-end=\"420\">The new SENNEBOGEN 822G is a powerful and efficient material handler for demanding recycling and material processing applications. This paper offers in-depth info on SENNEBOGEN 822G&#8217;s specifications and performance metrics. With a reach of up to 10m and a robust 22-ton design, this next-generation machine builds on the proven success of the 818E, incorporating the latest G-series innovations for enhanced durability, performance, and efficiency.<\/p>\n<p data-start=\"422\" data-end=\"812\">Featuring intelligent machine design and high-quality components, it delivers exceptional reliability, making it a standout in the latest machine generation from 2022 to 2025,\u00a0with an operating weight that enhances its performance. Its advanced hydraulic system and diesel engine provide maximum productivity while keeping energy consumption low, which is ideal for continuous operation. Designed with operator comfort in mind, the SENNEBOGEN 822 G offers excellent visibility, intuitive controls, and a smooth operating experience for demanding continuous tasks, ensuring maximum operator comfort.<\/p>\n\n\t\t\t\t\t\t\t<p>\n\t\t\t\t\t<a href=\"#\" class=\"new-button quote fancybox\" data-fancybox=\"quote-block_719f7c96c44608bbdabe6e6fe2585796\" data-src=\"#quote-block_719f7c96c44608bbdabe6e6fe2585796\">Get a quote today<\/a>\n\t\t\t\t<\/p>\n\t\t\t\t<div style=\"display:none\" class=\"fancybox-hidden\">\n\t\t\t\t\t<div id=\"quote-block_719f7c96c44608bbdabe6e6fe2585796\">\n\t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1020-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1020\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/51857#wpcf7-f1020-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1020\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1020-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Quote_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Quote_Form\" type=\"hidden\" name=\"form-type\" \/>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p><input type=\"hidden\" name=\"some_modelr\" id=\"some_modelr\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small>I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small>I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div>\n\t\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"updatesh\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div>\n\t\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 822G\"\/><\/span>\n\t\t<\/div>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"submit enquiry\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:none;font-size:16px;padding:0 20px 40px;\">Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\">Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and events.<\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div style=\"height:70px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Sennebogen 822G&#8217;s Key Features<\/h2>\n\n\n\n<section class=\"grid-flip-block-section no-color  block-padding-bottom-20\">\n    <div class=\"container\">\n                    <div class=\"grid-flip-block-container\" style=\"--current: var(--default); --current-small: var(--default-small);\">\n                                    <div class=\"grid-flip-block-base grid-block-1\" data-aos=\"fade-right\">\n                        <div class=\"wrapper-3d\">\n\n                            <div class=\"grid-flip-front\" style=\"\n                                background-image: linear-gradient(180deg, #29363E00 0%, #2F3C43 100%), url('https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/07\/DJI_0945.jpg');\n                                background-repeat: no-repeat;\n                                display: flex;\n                                background-size: cover;\n                                background-position: center;\n                                flex-direction: column;\n                                justify-content: end;\">\n\n                                <div class=\"grid-item-elements front\" data-aos=\"fade-right\">\n                                    \n                                    <div class=\"card-counter-large aos-init aos-animate\" data-aos=\"fade-up\">\n                                        <div class=\"card-next\">\n                                            <img decoding=\"async\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/themes\/molson\/img\/mobile-menu-arrow.svg\" alt=\"Molson Arrow\"\/>\n                                        <\/div>\n                                    <\/div>\n\n                                                                            <h2 class=\"grid-title\">Low Operating Machine Costs<\/h2>\n                                                                    <\/div>\n                            <\/div>\n\n                            <div class=\"grid-flip-back\">\n                                <div class=\"grid-item-elements\" data-aos=\"fade-right\">\n                                    <div class=\"grid-item-wrapper\">\n                                        <div class=\"grid-description\">\n                                                                                            <h2 class=\"grid-title\">Low Operating Machine Costs<\/h2>\n                                            \n                                            <p>The SENNEBOGEN 822G is designed efficiently, helping keep operating costs low without sacrificing performance, making it an ideal choice for dealers looking to see detailed specifications and technical data. Its fuel-efficient Cummins B 3.8 engine minimises fuel consumption, reducing overall expenses while maintaining the power needed for demanding material-handling tasks, including timber and scrap metal. High-quality, robust components and a streamlined design reduce wear and tear, leading to lower maintenance costs and longer service life, enhancing the overall value of your 22 t material handler, particularly for sorting applications. These features make it a cost-effective choice for businesses in the recycling and scrap industry looking to maximise the value of their SENNEBOGEN 822G and their return on investment, especially in scrap metal handling.<\/p>\n\n                                                                                            <a href=\"#\" class=\"grid-button quote fancybox\" data-fancybox=\"quote-block_5ef6ca41777dba81d6570744f0511a18083357a1051\" data-src=\"#quote-block_5ef6ca41777dba81d6570744f0511a18083357a1051\">REQUEST A QUOTE<\/a>\n\n                                                <div style=\"display:none\" class=\"fancybox-hidden\">\n                                                    <div id=\"quote-block_5ef6ca41777dba81d6570744f0511a18083357a1051\">\n                                                        \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1020-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1020\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/51857#wpcf7-f1020-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1020\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1020-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Quote_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Quote_Form\" type=\"hidden\" name=\"form-type\" \/>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p><input type=\"hidden\" name=\"some_modelr\" id=\"some_modelr\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small>I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small>I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div>\n\t\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div>\n\t\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 822G\"\/><\/span>\n\t\t<\/div>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"submit enquiry\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:none;font-size:16px;padding:0 20px 40px;\">Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\">Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and events.<\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n                                        <div class=\"grid-flip-block-base grid-block-2\" data-aos=\"fade-left\">\n                        <div class=\"wrapper-3d\">\n\n                            <div class=\"grid-flip-front\" style=\"\n                                background-image: linear-gradient(180deg, #29363E00 0%, #2F3C43 100%), url('https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/07\/Hydraulic-System@3x.png');\n                                background-repeat: no-repeat;\n                                display: flex;\n                                background-size: cover;\n                                background-position: center;\n                                flex-direction: column;\n                                justify-content: end;\">\n\n                                <div class=\"grid-item-elements front\" data-aos=\"fade-left\">\n                                    \n                                    <div class=\"card-counter-large aos-init aos-animate\" data-aos=\"fade-up\">\n                                        <div class=\"card-next\">\n                                            <img decoding=\"async\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/themes\/molson\/img\/mobile-menu-arrow.svg\" alt=\"Molson Arrow\"\/>\n                                        <\/div>\n                                    <\/div>\n\n                                                                            <h2 class=\"grid-title\">Smart Hydraulic System<\/h2>\n                                                                    <\/div>\n                            <\/div>\n\n                            <div class=\"grid-flip-back\">\n                                <div class=\"grid-item-elements\" data-aos=\"fade-left\">\n                                    <div class=\"grid-item-wrapper\">\n                                        <div class=\"grid-description\">\n                                                                                            <h2 class=\"grid-title\">Smart Hydraulic System<\/h2>\n                                            \n                                            <p>The Sennebogen 822G features intelligent hydraulics for efficient power use in waste and scrap metal handling. Its robust boom offers reach, precision, and durability. Engineered for fuel efficiency and operator comfort, it\u2019s also available with electric drive to reduce emissions and running costsideal for high-performance material handling.<\/p>\n\n                                                                                            <a href=\"#\" class=\"grid-button quote fancybox\" data-fancybox=\"quote-block_5ef6ca41777dba81d6570744f0511a18083357a1052\" data-src=\"#quote-block_5ef6ca41777dba81d6570744f0511a18083357a1052\">REQUEST A QUOTE<\/a>\n\n                                                <div style=\"display:none\" class=\"fancybox-hidden\">\n                                                    <div id=\"quote-block_5ef6ca41777dba81d6570744f0511a18083357a1052\">\n                                                        \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1020-o3\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1020\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/51857#wpcf7-f1020-o3\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1020\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1020-o3\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Quote_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Quote_Form\" type=\"hidden\" name=\"form-type\" \/>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p><input type=\"hidden\" name=\"some_modelr\" id=\"some_modelr\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small>I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small>I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div>\n\t\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div>\n\t\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 822G\"\/><\/span>\n\t\t<\/div>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"submit enquiry\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:none;font-size:16px;padding:0 20px 40px;\">Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\">Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and events.<\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n                                        <div class=\"grid-flip-block-base grid-block-3\" data-aos=\"fade-up\">\n                        <div class=\"wrapper-3d\">\n\n                            <div class=\"grid-flip-front\" style=\"\n                                background-image: linear-gradient(180deg, #29363E00 0%, #2F3C43 100%), url('https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/07\/Maxcab@3x.png');\n                                background-repeat: no-repeat;\n                                display: flex;\n                                background-size: cover;\n                                background-position: center;\n                                flex-direction: column;\n                                justify-content: end;\">\n\n                                <div class=\"grid-item-elements front\" data-aos=\"fade-up\">\n                                    \n                                    <div class=\"card-counter-large aos-init aos-animate\" data-aos=\"fade-up\">\n                                        <div class=\"card-next\">\n                                            <img decoding=\"async\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/themes\/molson\/img\/mobile-menu-arrow.svg\" alt=\"Molson Arrow\"\/>\n                                        <\/div>\n                                    <\/div>\n\n                                                                            <h2 class=\"grid-title\">The Sennebogen 822G&#039;s MaxCab Design<\/h2>\n                                                                    <\/div>\n                            <\/div>\n\n                            <div class=\"grid-flip-back\">\n                                <div class=\"grid-item-elements\" data-aos=\"fade-up\">\n                                    <div class=\"grid-item-wrapper\">\n                                        <div class=\"grid-description\">\n                                                                                            <h2 class=\"grid-title\">The Sennebogen 822G&#039;s MaxCab Design<\/h2>\n                                            \n                                            <p>The Sennebogen 822G features the Maxcab, an elevated, tiltable cabin designed for comfort, safety, and visibility. It includes an air-suspension seat, joystick controls, and a clear display for smooth operation. Impact-resistant windows, climate control, and soundproofing ensure all-day comfort, while its durable build boosts efficiency in demanding material handling tasks.<\/p>\n\n                                                                                            <a href=\"#\" class=\"grid-button quote fancybox\" data-fancybox=\"quote-block_5ef6ca41777dba81d6570744f0511a18083357a1053\" data-src=\"#quote-block_5ef6ca41777dba81d6570744f0511a18083357a1053\">REQUEST A QUOTE<\/a>\n\n                                                <div style=\"display:none\" class=\"fancybox-hidden\">\n                                                    <div id=\"quote-block_5ef6ca41777dba81d6570744f0511a18083357a1053\">\n                                                        \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1020-o4\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1020\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/51857#wpcf7-f1020-o4\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1020\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1020-o4\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Quote_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Quote_Form\" type=\"hidden\" name=\"form-type\" \/>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p><input type=\"hidden\" name=\"some_modelr\" id=\"some_modelr\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small>I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small>I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div>\n\t\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div>\n\t\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 822G\"\/><\/span>\n\t\t<\/div>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"submit enquiry\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:none;font-size:16px;padding:0 20px 40px;\">Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\">Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and events.<\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n\n                        <\/div>\n                    <\/div>\n                                <\/div>\n            <\/div>\n<\/section>\n\n\n<section class=\"bh-new no-color block-padding-top-20 block-padding-bottom-50\">\n\t<div class=\"container no-color image-right\">\n\t\t\t\t\t<div class=\"bh-image\" style=\"background-image: url('https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/07\/Sennebogen-822g_0000_DSC07801-1-720x586.png');\">\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"bh-content bh-centered \">\n\t\t\t<h2 data-start=\"40\" data-end=\"420\"><strong data-start=\"1645\" data-end=\"1655\">Safety first with the Sennebogen 822G<\/strong><\/h2>\n<p data-start=\"40\" data-end=\"420\">Operator safety is at the core of the design, ensuring compliance with the latest technical data for the Sennebogen 822G, including specifications for electric drive systems. The machine features an elevated cab for improved visibility, reducing blind spots and enhancing situational awareness.\u00a0Large windows, optional 360-degree camera systems, and reinforced structures provide added protection in demanding environments, ensuring safety during elevation tasks with our state-of-the-art excavator features. Stability is further enhanced through a well-balanced design in the SENNEBOGEN 822G, reducing the risk of tipping or instability during demanding continuous operation, which is vital for handling waste and scrap. These safety-focused elements help create a secure and efficient working environment for operators, ensuring optimal retention of safety standards.<\/p>\n\n\t\t\t\t\t\t\t<p>\n\t\t\t\t\t<a href=\"#\" class=\"new-button quote fancybox\" data-fancybox=\"quote-block_2c0533853b3e70db3d00aaeeefcdda0e\" data-src=\"#quote-block_2c0533853b3e70db3d00aaeeefcdda0e\">Get a quote today<\/a>\n\t\t\t\t<\/p>\n\t\t\t\t<div style=\"display:none\" class=\"fancybox-hidden\">\n\t\t\t\t\t<div id=\"quote-block_2c0533853b3e70db3d00aaeeefcdda0e\">\n\t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1020-o5\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1020\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/51857#wpcf7-f1020-o5\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1020\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1020-o5\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Quote_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Quote_Form\" type=\"hidden\" name=\"form-type\" \/>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p><input type=\"hidden\" name=\"some_modelr\" id=\"some_modelr\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small>I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small>I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div>\n\t\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div>\n\t\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 822G\"\/><\/span>\n\t\t<\/div>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"submit enquiry\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:none;font-size:16px;padding:0 20px 40px;\">Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\">Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and events.<\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"video-carousel-section no-color  block-padding-bottom-50\">\n    <div class=\"container\">\n        <h2 class=\"video-title\">Powerful and efficient in every recycling task<\/h2>\n        <div class=\"video-container\" data-aos=\"fade-up\">\n            <div class=\"loader-wrapper\" style=\"background-image: linear-gradient(rgba(85, 99, 108, 0.41)), url(&#039;https:\/\/img.youtube.com\/vi\/E4NNlTtO3Sw\/hqdefault.jpg&#039;); background-size: cover; background-position: center;\">\n                <div class=\"loader-backdrop\"><\/div>\n                <div class=\"loader-container\">\n                    <div class=\"loader\"><\/div>\n                <\/div>\n            <\/div>\n                            <iframe loading=\"lazy\" class=\"yt-frame\" id=\"main-play\" width=\"100%\" height=\"auto\" src=\"https:\/\/www.youtube.com\/embed\/E4NNlTtO3Sw\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n                    <\/div>\n\n        <div class=\"video-carousel-container\">\n            <div class=\"card-counter-large\" data-aos=\"fade-up\">\n                <div class=\"card-prev\">\n                    <img decoding=\"async\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/themes\/molson\/img\/mobile-menu-arrow.svg\" style=\"transform: scale(-1.0, 1.0);\" alt=\"Molson Arrow\"\/>\n                <\/div>\n                <div class=\"card-number\">\n                    <span><\/span>\n                <\/div>\n                <div class=\"card-next\">\n                    <img decoding=\"async\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/themes\/molson\/img\/mobile-menu-arrow.svg\" alt=\"Molson Arrow\"\/>\n                <\/div>\n            <\/div>\n\n            <div class=\"video-carousel\" data-aos=\"fade-left\">\n                <div class=\"swiper-wrapper\">\n                                            <div class=\"swiper-slide video-thumbnail\" style=\"background-image: linear-gradient(180deg, #29363E00 0%, #2E3B43 89%, #2F3C43 100%), url(&#039;https:\/\/img.youtube.com\/vi\/E4NNlTtO3Sw\/mqdefault.jpg&#039;); background-repeat: no-repeat; display: flex; align-items: center; background-size: cover; width: 250px !important;\">\n                            <a class=\"video-selector\" href=\"#\" data-id=\"E4NNlTtO3Sw\" data-title=\"Powerful and efficient in every recycling task\" aria-label=\"Powerful and efficient in every recycling task\"><\/a>\n                            <p>Powerful and efficient in every recycling task<\/p>\n                        <\/div>\n                                            <div class=\"swiper-slide video-thumbnail\" style=\"background-image: linear-gradient(180deg, #29363E00 0%, #2E3B43 89%, #2F3C43 100%), url(&#039;https:\/\/img.youtube.com\/vi\/DRsh9En-F54\/mqdefault.jpg&#039;); background-repeat: no-repeat; display: flex; align-items: center; background-size: cover; width: 250px !important;\">\n                            <a class=\"video-selector\" href=\"#\" data-id=\"DRsh9En-F54\" data-title=\"Sennebogen 822G at Austrian Recycling Facility\" aria-label=\"Sennebogen 822G at Austrian Recycling Facility\"><\/a>\n                            <p>Sennebogen 822G at Austrian Recycling Facility<\/p>\n                        <\/div>\n                                            <div class=\"swiper-slide video-thumbnail\" style=\"background-image: linear-gradient(180deg, #29363E00 0%, #2E3B43 89%, #2F3C43 100%), url(&#039;https:\/\/img.youtube.com\/vi\/AlybCR9beD8\/mqdefault.jpg&#039;); background-repeat: no-repeat; display: flex; align-items: center; background-size: cover; width: 250px !important;\">\n                            <a class=\"video-selector\" href=\"#\" data-id=\"AlybCR9beD8\" data-title=\"Maximum comfort and performance in recycling handling\" aria-label=\"Maximum comfort and performance in recycling handling\"><\/a>\n                            <p>Maximum comfort and performance in recycling handling<\/p>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<section class=\"news-block-section no-color block-padding-top-50 block-padding-bottom-50\">\n    <div class=\"news-container\">\n        <div class=\"news-row\">\n\n            <div class=\"news-header\" data-aos=\"fade-right\">\n                                    <div class=\"news-block-heading\">\n                        <h2>Stay Updated with the Latest on the Sennebogen 822G<\/h2>\n                    <\/div>\n                \n                                    <div class=\"news-block-description\">\n                        <p>Discover the latest news, stories, and updates from the Molson site. Whether it\u2019s product highlights, behind-the-scenes action, or industry insights, this is where you\u2019ll find everything connected to the 822G.<\/p>\n                    <\/div>\n                            <\/div>\n\n            <div class=\"news-header news-header-link\" data-aos=\"fade-right\">\n                                    <div class=\"news-block-link\">\n                        <a href=\"https:\/\/molsongroup.com\/category\/news\/\" target=\"_self\">\n                            View More News Here                        <\/a>\n                    <\/div>\n                            <\/div>\n\n                            <div class=\"news-swiper-block\">\n                    <div class=\"news-swiper\">\n                                                    <div class=\"news-col col-full\" data-aos=\"fade-up\">\n                                <a href=\"https:\/\/molsongroup.com\/new-sennebogen-material-handlers-boost-port-sutton-bridge\/\" class=\"news-url\">\n                                    <div class=\"news-item\">\n                                                                                    <img decoding=\"async\" class=\"news-image\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/2026\/03\/Port-Sutton-Bridge-_-Sennebogen-865E-Hybrid-38-300x169.jpg\" alt=\"New Sennebogen Material Handlers Boost Port Sutton Bridge\"\/>\n                                                                                <div class=\"news-text\">\n                                            <p class=\"news-title\">New Sennebogen Material Handlers Boost Port Sutton Bridge<\/p>\n                                            <p class=\"news-date\">\n                                                <img decoding=\"async\" class=\"news-date-icon\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/themes\/molson\/img\/news-date.svg\" alt=\"News calendar item date visual identifier icon\"\/>\n                                                February 4, 2026                                            <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"news-col\" data-aos=\"fade-up\">\n                                <a href=\"https:\/\/molsongroup.com\/sennebogen-865e-helps-fm-conway-maximise-self-sustainability\/\" class=\"news-url\">\n                                    <div class=\"news-item\">\n                                                                                    <img decoding=\"async\" class=\"news-image\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/2025\/12\/Sennebogen-865E-Helps-FM-Conway-Maximise-Self-Sustainability-300x169.jpg\" alt=\"Sennebogen 865E Helps FM Conway Maximise Self-Sustainability\"\/>\n                                                                                <div class=\"news-text\">\n                                            <p class=\"news-title\">Sennebogen 865E Helps FM Conway Maximise Self-Sustainability<\/p>\n                                            <p class=\"news-date\">\n                                                <img decoding=\"async\" class=\"news-date-icon\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/themes\/molson\/img\/news-date.svg\" alt=\"News calendar item date visual identifier icon\"\/>\n                                                November 24, 2025                                            <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"news-col\" data-aos=\"fade-up\">\n                                <a href=\"https:\/\/molsongroup.com\/sennebogen-molson-help-h-ripley-with-scrap-handling-growth\/\" class=\"news-url\">\n                                    <div class=\"news-item\">\n                                                                                    <img decoding=\"async\" class=\"news-image\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/2025\/12\/Sennebogen-Molson-Help-H.Ripley-With-Scrap-Handling-Growth-300x168.jpg\" alt=\"Sennebogen &amp; Molson Help H.Ripley With Scrap Handling Growth\"\/>\n                                                                                <div class=\"news-text\">\n                                            <p class=\"news-title\">Sennebogen &amp; Molson Help H.Ripley With Scrap Handling Growth<\/p>\n                                            <p class=\"news-date\">\n                                                <img decoding=\"async\" class=\"news-date-icon\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/themes\/molson\/img\/news-date.svg\" alt=\"News calendar item date visual identifier icon\"\/>\n                                                November 17, 2025                                            <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"news-col\" data-aos=\"fade-up\">\n                                <a href=\"https:\/\/molsongroup.com\/molson-leads-the-way-on-sustainability-with-sennebogen\/\" class=\"news-url\">\n                                    <div class=\"news-item\">\n                                                                                    <img decoding=\"async\" class=\"news-image\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/2025\/02\/IMG_20190719_095225-300x169.jpg\" alt=\"Sennebogen\"\/>\n                                                                                <div class=\"news-text\">\n                                            <p class=\"news-title\">Molson Leads the Way on Sustainability With Sennebogen<\/p>\n                                            <p class=\"news-date\">\n                                                <img decoding=\"async\" class=\"news-date-icon\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/themes\/molson\/img\/news-date.svg\" alt=\"News calendar item date visual identifier icon\"\/>\n                                                February 12, 2025                                            <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/a>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n\n<section class=\"gradient-section\" data-aos=\"fade-up\" style=\"--image: url('https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/07\/waste-and-recycling-industry-e1737546280551.jpg');\">\n    <div class=\"background-wrapper\">\n        <div class=\"container\">\n            <div class=\"gradient-text\">\n                <div class=\"gradient-heading\" data-aos=\"fade-up\">\n                    <h2>Waste &amp; Recycling Solutions Built for Your Industry<\/h2>\n                <\/div>\n                                    <div class=\"gradient-description\">\n                        <p>Looking for equipment tailored for the waste and recycling industry, including electric models for enhanced efficiency? At Molson Group, we provide a wide range of specialist machines designed to maximize efficiency in waste processing, material recovery, and recycling, including mobile options for various operating weights.. From shredders and screeners to electric material handlers and compactors, we have the right solutions to keep your work running smoothly. Explore our dedicated Waste &amp; Recycling industry page to find the perfect equipment, complete with detailed info on specifications and capabilities, including our latest electric drive models.<\/p>\n                    <\/div>\n                            <\/div>\n\n                            <div class=\"gradient-links\">\n                                            <a href=\"https:\/\/molsongroup.com\/industries\/waste-and-recycling\/\" target=\"_self\">\n                            Waste And Recycling                        <\/a>\n                    \n                                    <\/div>\n            \n                    <\/div>\n    <\/div>\n<\/section>\n\n\n<div class=\"container related-products-heading\" style=\"padding-top: 50px;\">\n    <h2>Related Products<\/h2>\n<\/div>\n\n    <section class=\"related-products no-color  block-padding-bottom-50\">\n        <div class=\"container\">\n                            <div class=\"three-piece-item\">\n                    <div class=\"piece-image\">\n                        <a href=\"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-830\/\" class=\"model\">\n                                                            <img decoding=\"async\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2019\/08\/Sennebogen-830e-Waste-Handler_working-ICON-720x586.jpg\" alt=\"Sennebogen 830e MOBILE\"\/>\n                                                    <\/a>\n                                                <a href=\"#\" class=\"btn-save\" data-id=\"614\" data-sid=\"2\"><\/a>\n                    <\/div>\n\n                    <div class=\"piece-details\">\n                        <h2>Sennebogen 830e MOBILE<\/h2>\n                                                    <h4>Waste Handlers<\/h4>\n                        \n                        <div class=\"piece-info-container\">\n                                                                                                <div class=\"info-row\">\n                                        <div class=\"info-label\">Model<\/div>\n                                        <div class=\"info-value\">830E Mobile<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Operating Weight (Kg)<\/div>\n                                        <div class=\"info-value\">38,500<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Max Range (m)<\/div>\n                                        <div class=\"info-value\">17<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Engine Type<\/div>\n                                        <div class=\"info-value\">Cummins 6.7<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Rated Engine Power Output<\/div>\n                                        <div class=\"info-value\">168 kW at 2200 rpm<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">European Emission Standard<\/div>\n                                        <div class=\"info-value\">Stage IV-compliant engine<\/div>\n                                    <\/div>\n                                                                                    <\/div>\n                    <\/div>\n\n                    <div class=\"piece-buttons\">\n                        <a href=\"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-830\/\" class=\"model\" aria-label=\"Sennebogen 830e MOBILE\">View Model<\/a>\n\n                                                    <a data-fancybox=\"brochure-614\" data-src=\"#brochure-614\" class=\"brochure fancybox\" href=\"#\"  aria-label=\"Sennebogen 830e MOBILE Brochure\">Download Brochure<\/a>\n                            <a href=\"#\" class=\"quote fancybox\" data-fancybox=\"quote-614\" data-src=\"#quote-614\"  aria-label=\"Sennebogen 830e MOBILE request a quote\">Request A Quote<\/a>\n                                            <\/div>\n\n                                            <div style=\"display:none\" class=\"fancybox-hidden\">\n                            <div id=\"brochure-614\">\n                                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f249-o6\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"249\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/51857#wpcf7-f249-o6\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"249\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f249-o6\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Brochure_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Brochure_Form\" type=\"hidden\" name=\"form-type\" \/>\n<p><span id=\"wpcf7-6a97df756fa91-wrapper\" class=\"wpcf7-form-control-wrap cf7apps-honeypot-wrap EmailAddress-wrap\" data-cf7apps-honeypot=\"EmailAddress\" style=\"position:absolute;width:1px;height:1px;padding:0;margin:-1px;overflow:hidden;clip:rect(0,0,0,0);white-space:nowrap;border:0;\"><input type=\"hidden\" name=\"EmailAddress-random-hash\" value=\"20260902\"\/><input type=\"hidden\" name=\"EmailAddress-time-token\" value=\"MTc4ODMzODAzNw==.5cb7606d480df735f2200f0aec01eb34389f20add4941ee669591a0a19a36cd6\"\/><label\n\t\t    for=\"wpcf7-6a97df756fa91-field\"\n\t\t    class=\"hp-message\">Please leave this field empty.<\/label><input id=\"wpcf7-6a97df756fa91-field\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"qvta24wtrdnp\"\n\t    value=\"\"\n\t    autocomplete=\"new-password\"\n\t    tabindex=\"1000\"\n\t    data-cf7apps-tabindex=\"1000\"\n    \/><\/span>\n<\/p>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<p><input type=\"hidden\" name=\"some_modeld\" id=\"some_modeld\" \/>\n\t\t<\/p>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small> I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small> I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<span class=\"wpcf7-form-control-wrap dg2-specification\" data-name=\"dg2-specification\"><input type=\"hidden\" name=\"dg2-specification\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\"\/><\/span>\n\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 822G\"\/><\/span>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"download brochure\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:100%;\"><small>Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\"> Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and <span onclick=\"getDoc()\">events<span>.<\/span><\/span><\/small><\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n<\/form>\n<\/div>\n                            <\/div>\n                        <\/div>\n                        <div style=\"display:none\" class=\"fancybox-hidden\">\n                            <div id=\"quote-614\">\n                                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1020-o7\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1020\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/51857#wpcf7-f1020-o7\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1020\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1020-o7\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Quote_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Quote_Form\" type=\"hidden\" name=\"form-type\" \/>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p><input type=\"hidden\" name=\"some_modelr\" id=\"some_modelr\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small>I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small>I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div>\n\t\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div>\n\t\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 822G\"\/><\/span>\n\t\t<\/div>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"submit enquiry\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:none;font-size:16px;padding:0 20px 40px;\">Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\">Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and events.<\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n                            <div class=\"three-piece-item\">\n                    <div class=\"piece-image\">\n                        <a href=\"https:\/\/molsongroup.com\/equipment\/products\/evoquip-caiman-150\/\" class=\"model\">\n                                                            <img decoding=\"async\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2024\/07\/Caiman-150-Ireland-CD-10-720x586.png\" alt=\"Terex EvoQuip Caiman 150\"\/>\n                                                    <\/a>\n                                                <a href=\"#\" class=\"btn-save\" data-id=\"9452\" data-sid=\"2\"><\/a>\n                    <\/div>\n\n                    <div class=\"piece-details\">\n                        <h2>Terex EvoQuip Caiman 150<\/h2>\n                                                    <h4>Shredders<\/h4>\n                        \n                        <div class=\"piece-info-container\">\n                                                                                                <div class=\"info-row\">\n                                        <div class=\"info-label\">Model<\/div>\n                                        <div class=\"info-value\">Caiman 150<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Speed<\/div>\n                                        <div class=\"info-value\">Slow Speed Shredder<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Weight (kg)<\/div>\n                                        <div class=\"info-value\">16,500<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Shaft Length (mm)<\/div>\n                                        <div class=\"info-value\">1500<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Engine<\/div>\n                                        <div class=\"info-value\">CAT C4.4<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Rated Engine Power Output<\/div>\n                                        <div class=\"info-value\">140kW Stage V<\/div>\n                                    <\/div>\n                                                                                    <\/div>\n                    <\/div>\n\n                    <div class=\"piece-buttons\">\n                        <a href=\"https:\/\/molsongroup.com\/equipment\/products\/evoquip-caiman-150\/\" class=\"model\" aria-label=\"Terex EvoQuip Caiman 150\">View Model<\/a>\n\n                                                    <a data-fancybox=\"brochure-9452\" data-src=\"#brochure-9452\" class=\"brochure fancybox\" href=\"#\"  aria-label=\"Terex EvoQuip Caiman 150 Brochure\">Download Brochure<\/a>\n                            <a href=\"#\" class=\"quote fancybox\" data-fancybox=\"quote-9452\" data-src=\"#quote-9452\"  aria-label=\"Terex EvoQuip Caiman 150 request a quote\">Request A Quote<\/a>\n                                            <\/div>\n\n                                            <div style=\"display:none\" class=\"fancybox-hidden\">\n                            <div id=\"brochure-9452\">\n                                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f249-o8\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"249\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/51857#wpcf7-f249-o8\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"249\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f249-o8\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Brochure_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Brochure_Form\" type=\"hidden\" name=\"form-type\" \/>\n<p><span id=\"wpcf7-6a97df75736b8-wrapper\" class=\"wpcf7-form-control-wrap cf7apps-honeypot-wrap EmailAddress-wrap\" data-cf7apps-honeypot=\"EmailAddress\" style=\"position:absolute;width:1px;height:1px;padding:0;margin:-1px;overflow:hidden;clip:rect(0,0,0,0);white-space:nowrap;border:0;\"><input type=\"hidden\" name=\"EmailAddress-random-hash\" value=\"20260902\"\/><input type=\"hidden\" name=\"EmailAddress-time-token\" value=\"MTc4ODMzODAzNw==.5cb7606d480df735f2200f0aec01eb34389f20add4941ee669591a0a19a36cd6\"\/><label\n\t\t    for=\"wpcf7-6a97df75736b8-field\"\n\t\t    class=\"hp-message\">Please leave this field empty.<\/label><input id=\"wpcf7-6a97df75736b8-field\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"qvta24wtrdnp\"\n\t    value=\"\"\n\t    autocomplete=\"new-password\"\n\t    tabindex=\"1000\"\n\t    data-cf7apps-tabindex=\"1000\"\n    \/><\/span>\n<\/p>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<p><input type=\"hidden\" name=\"some_modeld\" id=\"some_modeld\" \/>\n\t\t<\/p>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small> I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small> I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<span class=\"wpcf7-form-control-wrap dg2-specification\" data-name=\"dg2-specification\"><input type=\"hidden\" name=\"dg2-specification\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\"\/><\/span>\n\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 822G\"\/><\/span>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"download brochure\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:100%;\"><small>Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\"> Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and <span onclick=\"getDoc()\">events<span>.<\/span><\/span><\/small><\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n<\/form>\n<\/div>\n                            <\/div>\n                        <\/div>\n                        <div style=\"display:none\" class=\"fancybox-hidden\">\n                            <div id=\"quote-9452\">\n                                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1020-o9\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1020\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/51857#wpcf7-f1020-o9\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1020\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1020-o9\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Quote_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Quote_Form\" type=\"hidden\" name=\"form-type\" \/>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p><input type=\"hidden\" name=\"some_modelr\" id=\"some_modelr\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small>I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small>I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div>\n\t\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div>\n\t\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 822G\"\/><\/span>\n\t\t<\/div>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"submit enquiry\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:none;font-size:16px;padding:0 20px 40px;\">Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\">Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and events.<\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/section>\n","protected":false},"featured_media":48876,"template":"","meta":{"_acf_changed":false},"machine-category":[84],"class_list":["post-51857","products","type-products","status-publish","has-post-thumbnail","hentry","machine-category-waste-handlers"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sennebogen 822G Waste Handlers - Molson Equipment<\/title>\n<meta name=\"description\" content=\"Discover the Sennebogen 822 G 10m Reach Material Handler \u2013 built for efficient waste and scrap handling applications.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-822g\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sennebogen 822G Waste Handlers - Molson Equipment\" \/>\n<meta property=\"og:description\" content=\"Discover the Sennebogen 822 G 10m Reach Material Handler \u2013 built for efficient waste and scrap handling applications.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-822g\/\" \/>\n<meta property=\"og:site_name\" content=\"Molson Equipment\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MolsonGroup\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T10:30:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/07\/Sennebogen-822g_0000_DSC07801-1-1024x833.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"833\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-822g\\\/\",\"url\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-822g\\\/\",\"name\":\"Sennebogen 822G Waste Handlers - Molson Equipment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-822g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-822g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/Sennebogen-822g_0000_DSC07801-1.png\",\"datePublished\":\"2025-02-28T15:55:43+00:00\",\"dateModified\":\"2025-12-19T10:30:50+00:00\",\"description\":\"Discover the Sennebogen 822 G 10m Reach Material Handler \u2013 built for efficient waste and scrap handling applications.\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-822g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-822g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/Sennebogen-822g_0000_DSC07801-1.png\",\"contentUrl\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/Sennebogen-822g_0000_DSC07801-1.png\",\"width\":2359,\"height\":1920},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#website\",\"url\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/\",\"name\":\"Molson Equipment\",\"description\":\"Molson Equipment are the Construction, Plant Hire, Demolition Groundworks machinery experts\",\"publisher\":{\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#organization\",\"name\":\"Molson Equipment\",\"url\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/09\\\/Molson_EQUIPMENT_mark_CMYK.svg\",\"contentUrl\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/09\\\/Molson_EQUIPMENT_mark_CMYK.svg\",\"width\":513,\"height\":106,\"caption\":\"Molson Equipment\"},\"image\":{\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MolsonGroup\\\/\",\"https:\\\/\\\/www.instagram.com\\\/molsongroup\\\/?hl=en\",\"https:\\\/\\\/www.youtube.com\\\/@molson_group\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sennebogen 822G Waste Handlers - Molson Equipment","description":"Discover the Sennebogen 822 G 10m Reach Material Handler \u2013 built for efficient waste and scrap handling applications.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-822g\/","og_locale":"en_GB","og_type":"article","og_title":"Sennebogen 822G Waste Handlers - Molson Equipment","og_description":"Discover the Sennebogen 822 G 10m Reach Material Handler \u2013 built for efficient waste and scrap handling applications.","og_url":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-822g\/","og_site_name":"Molson Equipment","article_publisher":"https:\/\/www.facebook.com\/MolsonGroup\/","article_modified_time":"2025-12-19T10:30:50+00:00","og_image":[{"width":1024,"height":833,"url":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/07\/Sennebogen-822g_0000_DSC07801-1-1024x833.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-822g\/","url":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-822g\/","name":"Sennebogen 822G Waste Handlers - Molson Equipment","isPartOf":{"@id":"https:\/\/molsongroup.com\/equipment\/#website"},"primaryImageOfPage":{"@id":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-822g\/#primaryimage"},"image":{"@id":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-822g\/#primaryimage"},"thumbnailUrl":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/07\/Sennebogen-822g_0000_DSC07801-1.png","datePublished":"2025-02-28T15:55:43+00:00","dateModified":"2025-12-19T10:30:50+00:00","description":"Discover the Sennebogen 822 G 10m Reach Material Handler \u2013 built for efficient waste and scrap handling applications.","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/molsongroup.com\/equipment\/products\/sennebogen-822g\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-822g\/#primaryimage","url":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/07\/Sennebogen-822g_0000_DSC07801-1.png","contentUrl":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/07\/Sennebogen-822g_0000_DSC07801-1.png","width":2359,"height":1920},{"@type":"WebSite","@id":"https:\/\/molsongroup.com\/equipment\/#website","url":"https:\/\/molsongroup.com\/equipment\/","name":"Molson Equipment","description":"Molson Equipment are the Construction, Plant Hire, Demolition Groundworks machinery experts","publisher":{"@id":"https:\/\/molsongroup.com\/equipment\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/molsongroup.com\/equipment\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/molsongroup.com\/equipment\/#organization","name":"Molson Equipment","url":"https:\/\/molsongroup.com\/equipment\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/molsongroup.com\/equipment\/#\/schema\/logo\/image\/","url":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2023\/09\/Molson_EQUIPMENT_mark_CMYK.svg","contentUrl":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2023\/09\/Molson_EQUIPMENT_mark_CMYK.svg","width":513,"height":106,"caption":"Molson Equipment"},"image":{"@id":"https:\/\/molsongroup.com\/equipment\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MolsonGroup\/","https:\/\/www.instagram.com\/molsongroup\/?hl=en","https:\/\/www.youtube.com\/@molson_group"]}]}},"_links":{"self":[{"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/products\/51857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/media\/48876"}],"wp:attachment":[{"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/media?parent=51857"}],"wp:term":[{"taxonomy":"machine-category","embeddable":true,"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/machine-category?post=51857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}