{"id":20650,"date":"2025-01-20T09:44:39","date_gmt":"2025-01-20T09:44:39","guid":{"rendered":"https:\/\/molsongroup.co.uk\/equipment\/?post_type=products&#038;p=20650"},"modified":"2025-10-08T14:33:24","modified_gmt":"2025-10-08T14:33:24","slug":"sennebogen-817e-electro-battery-2","status":"publish","type":"products","link":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-817e-electro-battery-2\/","title":{"rendered":"Sennebogen 817E Electro Battery"},"content":{"rendered":"\n<div class=\"container related-products-heading\" style=\"padding-top: 50px;\">\n    <h2>Related Products<\/h2>\n<\/div>\n\n    <section class=\"related-products no-color\">\n        <div class=\"container\">\n                            <div class=\"three-piece-item\">\n                    <div class=\"piece-image\">\n                        <a href=\"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-821\/\" class=\"model\">\n                                                            <img decoding=\"async\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2019\/08\/Sennebogen-821e-Waste-Handler_working-ICON-720x586.jpg\" alt=\"Sennebogen 821E MOBILE\"\/>\n                                                    <\/a>\n                                                <a href=\"#\" class=\"btn-save\" data-id=\"610\" data-sid=\"2\"><\/a>\n                    <\/div>\n\n                    <div class=\"piece-details\">\n                        <h2>Sennebogen 821E MOBILE<\/h2>\n                                                    <h4>Waste Handlers<\/h4>\n                        \n                        <div class=\"piece-info-container\">\n                                                                                                <div class=\"info-row\">\n                                        <div class=\"info-label\">Model<\/div>\n                                        <div class=\"info-value\">821E Mobile<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Operating Weight (Kg)<\/div>\n                                        <div class=\"info-value\">23,900<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Max Range (m)<\/div>\n                                        <div class=\"info-value\">12<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Engine Type<\/div>\n                                        <div class=\"info-value\">Cummins QSB 4.5 <\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">Rated Engine Power Output<\/div>\n                                        <div class=\"info-value\">97 kW\/130 hp at 2,200 rpm<\/div>\n                                    <\/div>\n                                                                    <div class=\"info-row\">\n                                        <div class=\"info-label\">European Emission Standard<\/div>\n                                        <div class=\"info-value\">Stage IV-compliant engine<\/div>\n                                    <\/div>\n                                                                                    <\/div>\n                    <\/div>\n\n                    <div class=\"piece-buttons\">\n                        <a href=\"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-821\/\" class=\"model\" aria-label=\"Sennebogen 821E MOBILE\">View Model<\/a>\n\n                                                    <a data-fancybox=\"brochure-610\" data-src=\"#brochure-610\" class=\"brochure fancybox\" href=\"#\"  aria-label=\"Sennebogen 821E MOBILE Brochure\">Download Brochure<\/a>\n                            <a href=\"#\" class=\"quote fancybox\" data-fancybox=\"quote-610\" data-src=\"#quote-610\"  aria-label=\"Sennebogen 821E MOBILE request a quote\">Request A Quote<\/a>\n                                            <\/div>\n\n                                            <div style=\"display:none\" class=\"fancybox-hidden\">\n                            <div id=\"brochure-610\">\n                                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f249-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"249\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/20650#wpcf7-f249-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"249\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f249-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Brochure_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Brochure_Form\" type=\"hidden\" name=\"form-type\" \/>\n<p><span id=\"wpcf7-6a97df417ac17-wrapper\" class=\"wpcf7-form-control-wrap cf7apps-honeypot-wrap EmailAddress-wrap\" data-cf7apps-honeypot=\"EmailAddress\" style=\"position:absolute;width:1px;height:1px;padding:0;margin:-1px;overflow:hidden;clip:rect(0,0,0,0);white-space:nowrap;border:0;\"><input type=\"hidden\" name=\"EmailAddress-random-hash\" value=\"20260902\"\/><input type=\"hidden\" name=\"EmailAddress-time-token\" value=\"MTc4ODMzNzk4NQ==.4dd02de8de78375f18111133df3aec035881a22d15e6e2b61245988728b6ca35\"\/><label\n\t\t    for=\"wpcf7-6a97df417ac17-field\"\n\t\t    class=\"hp-message\">Please leave this field empty.<\/label><input id=\"wpcf7-6a97df417ac17-field\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"qvta24wtrdnp\"\n\t    value=\"\"\n\t    autocomplete=\"new-password\"\n\t    tabindex=\"1000\"\n\t    data-cf7apps-tabindex=\"1000\"\n    \/><\/span>\n<\/p>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<p><input type=\"hidden\" name=\"some_modeld\" id=\"some_modeld\" \/>\n\t\t<\/p>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small> I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small> I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"updatesh\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<span class=\"wpcf7-form-control-wrap dg2-specification\" data-name=\"dg2-specification\"><input type=\"hidden\" name=\"dg2-specification\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\"\/><\/span>\n\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 817E Electro Battery\"\/><\/span>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"download brochure\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:100%;\"><small>Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\"> Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and <span onclick=\"getDoc()\">events<span>.<\/span><\/span><\/small><\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n<\/form>\n<\/div>\n                            <\/div>\n                        <\/div>\n                        <div style=\"display:none\" class=\"fancybox-hidden\">\n                            <div id=\"quote-610\">\n                                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1020-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1020\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/20650#wpcf7-f1020-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1020\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1020-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Quote_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Quote_Form\" type=\"hidden\" name=\"form-type\" \/>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p><input type=\"hidden\" name=\"some_modelr\" id=\"some_modelr\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small>I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small>I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div>\n\t\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div>\n\t\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 817E Electro Battery\"\/><\/span>\n\t\t<\/div>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"submit enquiry\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:none;font-size:16px;padding:0 20px 40px;\">Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\">Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and events.<\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n                            <div class=\"three-piece-item\">\n                    <div class=\"piece-image\">\n                        <a href=\"https:\/\/molsongroup.com\/equipment\/products\/rotobec-selector-grabs\/\" class=\"model\">\n                                                            <img decoding=\"async\" src=\"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2021\/04\/Rotobec_Selector-Grabs_working-1-720x586.jpg\" alt=\"ROTOBEC SELECTOR GRABS\"\/>\n                                                    <\/a>\n                                                <a href=\"#\" class=\"btn-save\" data-id=\"4345\" data-sid=\"2\"><\/a>\n                    <\/div>\n\n                    <div class=\"piece-details\">\n                        <h2>ROTOBEC SELECTOR GRABS<\/h2>\n                                                    <h4>Attachments<\/h4>\n                        \n                        <div class=\"piece-info-container\">\n                                                    <\/div>\n                    <\/div>\n\n                    <div class=\"piece-buttons\">\n                        <a href=\"https:\/\/molsongroup.com\/equipment\/products\/rotobec-selector-grabs\/\" class=\"model\" aria-label=\"ROTOBEC SELECTOR GRABS\">View Model<\/a>\n\n                                                    <a data-fancybox=\"brochure-4345\" data-src=\"#brochure-4345\" class=\"brochure fancybox\" href=\"#\"  aria-label=\"ROTOBEC SELECTOR GRABS Brochure\">Download Brochure<\/a>\n                            <a href=\"#\" class=\"quote fancybox\" data-fancybox=\"quote-4345\" data-src=\"#quote-4345\"  aria-label=\"ROTOBEC SELECTOR GRABS request a quote\">Request A Quote<\/a>\n                                            <\/div>\n\n                                            <div style=\"display:none\" class=\"fancybox-hidden\">\n                            <div id=\"brochure-4345\">\n                                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f249-o3\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"249\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/20650#wpcf7-f249-o3\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"249\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f249-o3\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Brochure_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Brochure_Form\" type=\"hidden\" name=\"form-type\" \/>\n<p><span id=\"wpcf7-6a97df417f90c-wrapper\" class=\"wpcf7-form-control-wrap cf7apps-honeypot-wrap EmailAddress-wrap\" data-cf7apps-honeypot=\"EmailAddress\" style=\"position:absolute;width:1px;height:1px;padding:0;margin:-1px;overflow:hidden;clip:rect(0,0,0,0);white-space:nowrap;border:0;\"><input type=\"hidden\" name=\"EmailAddress-random-hash\" value=\"20260902\"\/><input type=\"hidden\" name=\"EmailAddress-time-token\" value=\"MTc4ODMzNzk4NQ==.4dd02de8de78375f18111133df3aec035881a22d15e6e2b61245988728b6ca35\"\/><label\n\t\t    for=\"wpcf7-6a97df417f90c-field\"\n\t\t    class=\"hp-message\">Please leave this field empty.<\/label><input id=\"wpcf7-6a97df417f90c-field\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"qvta24wtrdnp\"\n\t    value=\"\"\n\t    autocomplete=\"new-password\"\n\t    tabindex=\"1000\"\n\t    data-cf7apps-tabindex=\"1000\"\n    \/><\/span>\n<\/p>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<p><input type=\"hidden\" name=\"some_modeld\" id=\"some_modeld\" \/>\n\t\t<\/p>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small> I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small> I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<span class=\"wpcf7-form-control-wrap dg2-specification\" data-name=\"dg2-specification\"><input type=\"hidden\" name=\"dg2-specification\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\"\/><\/span>\n\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 817E Electro Battery\"\/><\/span>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"download brochure\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:100%;\"><small>Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\"> Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and <span onclick=\"getDoc()\">events<span>.<\/span><\/span><\/small><\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n<\/form>\n<\/div>\n                            <\/div>\n                        <\/div>\n                        <div style=\"display:none\" class=\"fancybox-hidden\">\n                            <div id=\"quote-4345\">\n                                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1020-o4\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1020\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/equipment\/wp-json\/wp\/v2\/products\/20650#wpcf7-f1020-o4\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1020\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1020-o4\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment_Quote_Form\" type=\"hidden\" name=\"form-name\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Equipment\" type=\"hidden\" name=\"form-division\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Quote_Form\" type=\"hidden\" name=\"form-type\" \/>\n<section class=\"form-container\">\n\t<div class=\"container\">\n\t\t<div class=\"basic-details\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone number*\" value=\"\" type=\"text\" name=\"phone-number\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"country\"><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Europe\">Europe<\/option><option value=\"Australia\">Australia<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"postcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Post code*\" value=\"\" type=\"text\" name=\"postcode\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t\t<p><input type=\"hidden\" name=\"some_modelr\" id=\"some_modelr\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"agreement-container\" style=\"width:100%;float:none;\">\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div style=\"width:100%;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" value=\"0\" class=\"rupdatesr\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">Yes,<small>I\u2019d like to receive updates, offers and information in the future.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t<div style=\"clear:both;\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div style=\"width:100%; display:block;\">\n\t\t\t\t\t<p><input type=\"radio\" name=\"rupdates\" class=\"rupdatesr\" value=\"1\" style=\"width:40px;margin-top:4px;\" \/><label for=\"rupdates\" class=\"rupdatesl\">No thanks, <small>I would not like to receive any information from Molson other than to process my immediate enquiry.<\/small>*<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<div>\n\t\t\t\t<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"updatesh\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div id=\"updatesm\" style=\"color:red;\">\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"form-full-row\">\n\t\t\t\t<div>\n\t\t\t\t\t<p><label>Mandatory *<\/label>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div>\n\t\t<span class=\"wpcf7-form-control-wrap dg2-post-title\" data-name=\"dg2-post-title\"><input type=\"hidden\" name=\"dg2-post-title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Sennebogen 817E Electro Battery\"\/><\/span>\n\t\t<\/div>\n\t\t<div class=\"submit-container\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"submit enquiry\" \/><br \/>\n<label>Alternatively call us directly<br \/>\nTel +44 (0) 1179 820123<\/label><br \/>\n<label style=\"max-width:none;font-size:16px;padding:0 20px 40px;\">Your personal information will be processed by Molson Group in accordance with the Molson Group <a href=\"https:\/\/molsongroup.com\/privacy-policy\/\">Privacy<\/a> and <a href=\"https:\/\/molsongroup.com\/retention-policy\/\">Retention Policies<\/a>. Molson Group would like to send you relevant direct marketing communications by phone, email or text message about our latest products, services, offers, news and events.<\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/section>\n","protected":false},"featured_media":20651,"template":"","meta":{"_acf_changed":false},"machine-category":[84],"class_list":["post-20650","products","type-products","status-publish","has-post-thumbnail","hentry","machine-category-waste-handlers"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sennebogen 817E Electro Battery Waste Handlers - Molson Equipment<\/title>\n<meta name=\"description\" content=\"New Sennebogen 817E Electro Battery Waste Handlers from the Machinery and Equipment Experts Molson Equipment\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-817e-electro-battery-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sennebogen 817E Electro Battery Waste Handlers - Molson Equipment\" \/>\n<meta property=\"og:description\" content=\"New Sennebogen 817E Electro Battery Waste Handlers from the Machinery and Equipment Experts Molson Equipment\" \/>\n<meta property=\"og:url\" content=\"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-817e-electro-battery-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Molson Equipment\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MolsonGroup\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T14:33:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/01\/817-Electro-Battery-Material-Handler.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"671\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-817e-electro-battery-2\\\/\",\"url\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-817e-electro-battery-2\\\/\",\"name\":\"Sennebogen 817E Electro Battery Waste Handlers - Molson Equipment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-817e-electro-battery-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-817e-electro-battery-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/01\\\/817-Electro-Battery-Material-Handler.jpeg\",\"datePublished\":\"2025-01-20T09:44:39+00:00\",\"dateModified\":\"2025-10-08T14:33:24+00:00\",\"description\":\"New Sennebogen 817E Electro Battery Waste Handlers from the Machinery and Equipment Experts Molson Equipment\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-817e-electro-battery-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/products\\\/sennebogen-817e-electro-battery-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/01\\\/817-Electro-Battery-Material-Handler.jpeg\",\"contentUrl\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/01\\\/817-Electro-Battery-Material-Handler.jpeg\",\"width\":671,\"height\":700},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#website\",\"url\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/\",\"name\":\"Molson Equipment\",\"description\":\"Molson Equipment are the Construction, Plant Hire, Demolition Groundworks machinery experts\",\"publisher\":{\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#organization\",\"name\":\"Molson Equipment\",\"url\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/09\\\/Molson_EQUIPMENT_mark_CMYK.svg\",\"contentUrl\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/09\\\/Molson_EQUIPMENT_mark_CMYK.svg\",\"width\":513,\"height\":106,\"caption\":\"Molson Equipment\"},\"image\":{\"@id\":\"https:\\\/\\\/molsongroup.com\\\/equipment\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MolsonGroup\\\/\",\"https:\\\/\\\/www.instagram.com\\\/molsongroup\\\/?hl=en\",\"https:\\\/\\\/www.youtube.com\\\/@molson_group\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sennebogen 817E Electro Battery Waste Handlers - Molson Equipment","description":"New Sennebogen 817E Electro Battery Waste Handlers from the Machinery and Equipment Experts Molson Equipment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-817e-electro-battery-2\/","og_locale":"en_GB","og_type":"article","og_title":"Sennebogen 817E Electro Battery Waste Handlers - Molson Equipment","og_description":"New Sennebogen 817E Electro Battery Waste Handlers from the Machinery and Equipment Experts Molson Equipment","og_url":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-817e-electro-battery-2\/","og_site_name":"Molson Equipment","article_publisher":"https:\/\/www.facebook.com\/MolsonGroup\/","article_modified_time":"2025-10-08T14:33:24+00:00","og_image":[{"width":671,"height":700,"url":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/01\/817-Electro-Battery-Material-Handler.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-817e-electro-battery-2\/","url":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-817e-electro-battery-2\/","name":"Sennebogen 817E Electro Battery Waste Handlers - Molson Equipment","isPartOf":{"@id":"https:\/\/molsongroup.com\/equipment\/#website"},"primaryImageOfPage":{"@id":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-817e-electro-battery-2\/#primaryimage"},"image":{"@id":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-817e-electro-battery-2\/#primaryimage"},"thumbnailUrl":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/01\/817-Electro-Battery-Material-Handler.jpeg","datePublished":"2025-01-20T09:44:39+00:00","dateModified":"2025-10-08T14:33:24+00:00","description":"New Sennebogen 817E Electro Battery Waste Handlers from the Machinery and Equipment Experts Molson Equipment","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/molsongroup.com\/equipment\/products\/sennebogen-817e-electro-battery-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/molsongroup.com\/equipment\/products\/sennebogen-817e-electro-battery-2\/#primaryimage","url":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/01\/817-Electro-Battery-Material-Handler.jpeg","contentUrl":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2025\/01\/817-Electro-Battery-Material-Handler.jpeg","width":671,"height":700},{"@type":"WebSite","@id":"https:\/\/molsongroup.com\/equipment\/#website","url":"https:\/\/molsongroup.com\/equipment\/","name":"Molson Equipment","description":"Molson Equipment are the Construction, Plant Hire, Demolition Groundworks machinery experts","publisher":{"@id":"https:\/\/molsongroup.com\/equipment\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/molsongroup.com\/equipment\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/molsongroup.com\/equipment\/#organization","name":"Molson Equipment","url":"https:\/\/molsongroup.com\/equipment\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/molsongroup.com\/equipment\/#\/schema\/logo\/image\/","url":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2023\/09\/Molson_EQUIPMENT_mark_CMYK.svg","contentUrl":"https:\/\/molsongroup.com\/equipment\/wp-content\/uploads\/sites\/2\/2023\/09\/Molson_EQUIPMENT_mark_CMYK.svg","width":513,"height":106,"caption":"Molson Equipment"},"image":{"@id":"https:\/\/molsongroup.com\/equipment\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MolsonGroup\/","https:\/\/www.instagram.com\/molsongroup\/?hl=en","https:\/\/www.youtube.com\/@molson_group"]}]}},"_links":{"self":[{"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/products\/20650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/media\/20651"}],"wp:attachment":[{"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/media?parent=20650"}],"wp:term":[{"taxonomy":"machine-category","embeddable":true,"href":"https:\/\/molsongroup.com\/equipment\/wp-json\/wp\/v2\/machine-category?post=20650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}